{"id":5609,"date":"2016-11-08T13:44:16","date_gmt":"2016-11-08T12:44:16","guid":{"rendered":"https:\/\/www.radbag.de\/blog\/?p=5609"},"modified":"2019-10-15T16:16:27","modified_gmt":"2019-10-15T14:16:27","slug":"rentier-geschenkboxen-printable","status":"publish","type":"post","link":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable","title":{"rendered":"Printable Rentier-Geschenkboxen Selbermachen"},"content":{"rendered":"<div class=\"bpp_post_wrapper\" data-bpp-pinlink=\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\" data-bpp-pincorner=\"northeast\" data-bpp-pinhover=\"true\" data-bpp-lang=\"en\" data-bpp-count=\"none\" data-bpp-zero-count=\"true\" data-bpp-size=\"28\" data-bpp-color=\"white\" data-bpp-mobile=\"1\"><p style=\"text-align: center;\">Du willst deine super Weihnachtsgeschenke auch noch cool verpacken? Dann bist du genau richtig! Hier findest du die Printable Rentier-Geschenkbox die du ganz einfach selber machen kannst. Und die macht unter dem Weihnachtsbaum wirklich was her. Das Printable stammt von\u00a0<a href=\"http:\/\/madame-citron.fr\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">madame citron<\/a>.<\/p>\n<h2 style=\"text-align: center;\">Rentier \u2013 Geschenkboxen Printable<\/h2>\n<p><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/0-resultat2.png\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-5611 aligncenter\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/0-resultat2.png\" border=\"0\" alt=\"0-resultat2\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/0-resultat2.png 800w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/0-resultat2-300x200.png 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/0-resultat2-720x480.png 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/0-resultat2-160x107.png 160w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Was du brauchst:<\/p>\n<ul>\n<li>Festes farbiges Papier (wei\u00df, beige, braun, dunkelbraun, gold)<\/li>\n<li>Kleber<\/li>\n<li>Schere<\/li>\n<li>Printable<\/li>\n<li>Schwarzen Marker<\/li>\n<li>Faltwerkzeug<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p>Vorgehensweise:<\/p>\n<ol>\n<li>Drucke die Printables aus, schneide es in die einzelnen Teile und verwende sie als Schablone um die Teile aus dem farbigen Papier auszuschneiden.<\/li>\n<\/ol>\n<p><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/1.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5612 aligncenter\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/1.png\" border=\"0\" alt=\"1\" width=\"495\" height=\"330\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/1.png 800w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/1-300x200.png 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/1-720x480.png 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/1-160x107.png 160w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/><\/a><\/p>\n<p>2. Beginne mit dem wei\u00dfen Feld \u2013 schneide die Form aus dem wei\u00dfen Papier aus, mache die Faltlinien, und klebe die Klappen an den Boden.<\/p>\n<div data-carousel-extra='{\"blog_id\":1,\"permalink\":\"https:\\\/\\\/www.radbag.de\\\/blog\\\/rentier-geschenkboxen-printable\",\"likes_blog_id\":false}' id='gallery-2' class='gallery galleryid-5609 gallery-columns-2 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\/2-5'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/2-250x250.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/2-250x250.png 250w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/2-480x480.png 480w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" data-attachment-id=\"5613\" data-orig-file=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/2.png\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2\" data-image-description=\"\" data-medium-file=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/2-300x200.png\" data-large-file=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/2.png\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\/3-5'><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/3-250x250.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/3-250x250.png 250w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/3-480x480.png 480w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" data-attachment-id=\"5614\" data-orig-file=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/3.png\" data-orig-size=\"800,533\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3\" data-image-description=\"\" data-medium-file=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/3-300x200.png\" data-large-file=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/3.png\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>3. F\u00fcge dann alle Teile des Rentierkopfes zusammen: Geweih, Ohren, Schnauze. Klebe den Kopf auf den wei\u00dfen Kasten und schlie\u00dfe die Box \u00fcber der Nase mit dem Schlitz.<\/p>\n<p><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/4.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5615 aligncenter\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/4.png\" border=\"0\" alt=\"4\" width=\"551\" height=\"367\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/4.png 800w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/4-300x200.png 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/4-720x480.png 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/4-160x107.png 160w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><\/a><\/p>\n<p>4. Zeichne die Nase und den Mund auf das Gesicht und fertig!<\/p>\n<p><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/5.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5616 aligncenter\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/5.png\" border=\"0\" alt=\"5\" width=\"666\" height=\"443\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/5.png 800w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/5-300x200.png 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/5-720x480.png 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/5-160x107.png 160w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/Rendier-doosjes-printable.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-5620 aligncenter\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/Download-button1.png\" border=\"0\" alt=\"Download-button(1)\" width=\"728\" height=\"144\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/Download-button1.png 789w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/Download-button1-300x59.png 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/Download-button1-720x142.png 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/10\/Download-button1-160x32.png 160w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/p>\n<hr \/>\n<p>Nat\u00fcrlich darf auch die richtige F\u00fcllung f\u00fcr deine coole Geschenkbox nicht fehlen, aber die findest du hier:<\/p>\n<p><a href=\"https:\/\/www.radbag.de\/weihnachtsgeschenke\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-6012 aligncenter\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/weihnachtsgeschenke.jpg\" border=\"0\" alt=\"weihnachtsgeschenke\" width=\"700\" height=\"200\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/weihnachtsgeschenke.jpg 700w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/weihnachtsgeschenke-300x86.jpg 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/weihnachtsgeschenke-160x46.jpg 160w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<hr \/>\n<p>\u00a0<\/p>\n<p>Dir gef\u00e4llt unser Blog und du m\u00f6chtest immer sehen, was es t\u00e4glich Neues gibt? Dann folge uns doch auf <strong>Bloglovin:<\/strong><\/p>\n<p><strong><a class=\"blsdk-follow\" href=\"https:\/\/www.bloglovin.com\/blogs\/radbag-blog-12710125\" target=\"_blank\" rel=\"noopener noreferrer\" data-blsdk-type=\"button\" data-blsdk-counter=\"false\">Follow<\/a><\/strong><\/p>\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2019\/10\/Rentier_Geschenkbox_288795846_1080x1080_F30.mp4\"><\/video><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Du willst deine super Weihnachtsgeschenke auch noch cool verpacken? Dann bist du genau richtig! Hier findest du die Printable Rentier-Geschenkbox die du ganz einfach selber machen kannst. Und die macht unter dem Weihnachtsbaum wirklich was her. Das Printable stammt von\u00a0madame citron. Rentier \u2013 Geschenkboxen Printable Was du brauchst: Festes farbiges Papier (wei\u00df, beige, braun, dunkelbraun,&hellip;<\/p>\n","protected":false},"author":14,"featured_media":10099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115,39],"tags":[176,26,177,174],"class_list":["post-5609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-free-printable","category-x-mas","tag-christmas","tag-free-printable","tag-gift-wrapping","tag-xmas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Printable Rentier - Geschenkboxen f\u00fcr Weihnachen<\/title>\n<meta name=\"description\" content=\"Du willst deine Weihnachtsgeschenke originell aber einfach verpacken? Hier findest du das Printable f\u00fcr die coolen Rentier-Geschenkboxen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Printable Rentier - Geschenkboxen f\u00fcr Weihnachen\" \/>\n<meta property=\"og:description\" content=\"Du willst deine Weihnachtsgeschenke originell aber einfach verpacken? Hier findest du das Printable f\u00fcr die coolen Rentier-Geschenkboxen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\" \/>\n<meta property=\"og:site_name\" content=\"Der Blog von radbag\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-08T12:44:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-15T14:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Johanna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\",\"url\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\",\"name\":\"Printable Rentier - Geschenkboxen f\u00fcr Weihnachen\",\"isPartOf\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg\",\"datePublished\":\"2016-11-08T12:44:16+00:00\",\"dateModified\":\"2019-10-15T14:16:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d\"},\"description\":\"Du willst deine Weihnachtsgeschenke originell aber einfach verpacken? Hier findest du das Printable f\u00fcr die coolen Rentier-Geschenkboxen!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#primaryimage\",\"url\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg\",\"contentUrl\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg\",\"width\":1000,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.radbag.de\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Printable Rentier-Geschenkboxen Selbermachen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radbag.de\/blog\/#website\",\"url\":\"https:\/\/www.radbag.de\/blog\/\",\"name\":\"Der Blog von radbag\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radbag.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d\",\"name\":\"Johanna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png\",\"contentUrl\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png\",\"caption\":\"Johanna\"},\"description\":\"Johanna k\u00fcmmert sich um alles was mit E-Commerce zu tun hat und verfasst f\u00fcr euch spannende Blogbeitr\u00e4ge die euer Leben leichter machen sollen. Wenn sie euch das Leben gerade nicht leichter macht, ist sie entweder auf der ganzen Welt oder am Tanzen zu finden.\",\"url\":\"https:\/\/www.radbag.de\/blog\/author\/johanna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Printable Rentier - Geschenkboxen f\u00fcr Weihnachen","description":"Du willst deine Weihnachtsgeschenke originell aber einfach verpacken? Hier findest du das Printable f\u00fcr die coolen Rentier-Geschenkboxen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable","og_locale":"de_DE","og_type":"article","og_title":"Printable Rentier - Geschenkboxen f\u00fcr Weihnachen","og_description":"Du willst deine Weihnachtsgeschenke originell aber einfach verpacken? Hier findest du das Printable f\u00fcr die coolen Rentier-Geschenkboxen!","og_url":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable","og_site_name":"Der Blog von radbag","article_published_time":"2016-11-08T12:44:16+00:00","article_modified_time":"2019-10-15T14:16:27+00:00","og_image":[{"width":1000,"height":648,"url":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg","type":"image\/jpeg"}],"author":"Johanna","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Johanna","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable","url":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable","name":"Printable Rentier - Geschenkboxen f\u00fcr Weihnachen","isPartOf":{"@id":"https:\/\/www.radbag.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#primaryimage"},"image":{"@id":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#primaryimage"},"thumbnailUrl":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg","datePublished":"2016-11-08T12:44:16+00:00","dateModified":"2019-10-15T14:16:27+00:00","author":{"@id":"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d"},"description":"Du willst deine Weihnachtsgeschenke originell aber einfach verpacken? Hier findest du das Printable f\u00fcr die coolen Rentier-Geschenkboxen!","breadcrumb":{"@id":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#primaryimage","url":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg","contentUrl":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2016\/11\/rentier-geschenkboxen.jpg","width":1000,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/www.radbag.de\/blog\/rentier-geschenkboxen-printable#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.radbag.de\/blog"},{"@type":"ListItem","position":2,"name":"Printable Rentier-Geschenkboxen Selbermachen"}]},{"@type":"WebSite","@id":"https:\/\/www.radbag.de\/blog\/#website","url":"https:\/\/www.radbag.de\/blog\/","name":"Der Blog von radbag","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radbag.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d","name":"Johanna","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png","contentUrl":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png","caption":"Johanna"},"description":"Johanna k\u00fcmmert sich um alles was mit E-Commerce zu tun hat und verfasst f\u00fcr euch spannende Blogbeitr\u00e4ge die euer Leben leichter machen sollen. Wenn sie euch das Leben gerade nicht leichter macht, ist sie entweder auf der ganzen Welt oder am Tanzen zu finden.","url":"https:\/\/www.radbag.de\/blog\/author\/johanna"}]}},"_links":{"self":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts\/5609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/comments?post=5609"}],"version-history":[{"count":13,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts\/5609\/revisions"}],"predecessor-version":[{"id":12148,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts\/5609\/revisions\/12148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/media\/10099"}],"wp:attachment":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/media?parent=5609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/categories?post=5609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/tags?post=5609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}