{"id":7882,"date":"2017-08-31T15:15:11","date_gmt":"2017-08-31T13:15:11","guid":{"rendered":"https:\/\/www.radbag.de\/blog\/?p=7882"},"modified":"2022-09-02T09:26:46","modified_gmt":"2022-09-02T07:26:46","slug":"oktoberfest-der-survival-guide","status":"publish","type":"post","link":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide","title":{"rendered":"Oktoberfest &#8211; Der Survival-Guide"},"content":{"rendered":"<div class=\"bpp_post_wrapper\" data-bpp-pinlink=\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide\" data-bpp-pincorner=\"northeast\" data-bpp-pinhover=\"true\" data-bpp-lang=\"en\" data-bpp-count=\"none\" data-bpp-zero-count=\"true\" data-bpp-size=\"28\" data-bpp-color=\"white\" data-bpp-mobile=\"1\">\n<h2 class=\"has-text-align-center wp-block-heading\">Oktoberfest<\/h2>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Wie du das Fest der Feste \u00fcberlebst<\/h3>\n\n\n\n<p class=\"has-text-align-left\">Der leckere Duft von W\u00fcrstchen in der Luft, die St\u00e4nde voller Brezel, der leicht s\u00fc\u00dfe Geschmack von Senf und die Menschenmenge in Dirndl und Lederhosen mit sch\u00f6nen Frisuren und Lebkuchenherzen um den Hals. Und nat\u00fcrlich Bier. Bier ohne Ende. Ja, wir sprechen hier vom ber\u00fchmt, ber\u00fcchtigten Oktoberfest, dem gr\u00f6\u00dften Volksfest in M\u00fcnchen. Wo Millionen von Menschen jedes Jahr aus der ganzen Welt anreisen, sich in Tracht werfen und ordentlich mit Bier und Wei\u00dfwurst das Wochenende feiern.<\/p>\n\n\n\n<p>Das Oktoberfest in M\u00fcnchen wird seit 1872 jeweils am ersten Samstag nach dem 15. September feierlich er\u00f6ffnet. Das Ende des Festes ist traditionell der erste Sonntag im Oktober. Also \u00fcber zwei Wochen lang, jeden Tag, zwischen Bier, Brezeln, Wei\u00dfw\u00fcrsten und jede Menge Attraktionen. Jedes Jahr&nbsp;pilgern, um&nbsp;die sechs Millionen Menschen nach Bayern um Teil dieses Ereignisses zu sein und zwischen 12.000 Angestellten so richtig auf den Putz zu hauen!<\/p>\n\n\n\n<p class=\"has-text-align-left\"><strong>Aber wie zum Teufel h\u00e4lt der Menschliche K\u00f6rper, deine Seele und dein Kopf das aus?<\/strong><\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\">Wir haben den ultimativen Oktoberfest Survival-Guide f\u00fcr euch!<\/h2>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"731\" height=\"1024\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3-731x1024.jpg\" alt=\"Oktoberfest\" class=\"wp-image-7886\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3-731x1024.jpg 731w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3-214x300.jpg 214w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3-720x1008.jpg 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3-160x224.jpg 160w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/main-image3.jpg 1000w\" sizes=\"auto, (max-width: 731px) 100vw, 731px\" \/><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">Zeig mir mehr >><\/a><\/div>\n<\/div>\n\n\n\n<p><strong>1.<\/strong> Du solltest dir unbedingt unseren &#8222;<a href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">personalisierbaren Bierkrug<\/a>&#8220; f\u00fcr dich und deine Wiese-Crew besorgen. Damit k\u00f6nnt ihr euer Training f\u00fcr das Oktoberfest so richtig beginnen lassen. Ich meine, du brauchst wohl einen eigenen Bierkrug.<\/p>\n\n\n\n<p><strong>2.<\/strong>\u00a0Damit du auch ja nicht dieses Wort Bier aus deinem Kopf verlierst, in keiner Sekunde des Tages, werden ab jetzt alle Mahlzeiten auf unserem &#8222;<a href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">Long live Beer, Pizza and Sex<\/a>&#8220; Schneidebrett vorbereitet. Die Pizza kannst du durch Wei\u00dfwurst ersetzen, der Rest d\u00fcrfe ziemlich gut passen.<\/p>\n\n\n\n<p><strong>3.<\/strong> Deine Tasse Kaffee am Morgen, wird ab sofort nicht mehr in der typischen Kaffeetasse getrunken, sondern in unserer &#8222;<a href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">Wish you were Beer<\/a>&#8220; Tasse. Damit sich Verstand und Seele schon darauf vorbereiten k\u00f6nnen, wie es sein wird, um neun Uhr morgens das erste Ma\u00df Bier in der Kehle zu sp\u00fcren.<\/p>\n\n\n\n<p><strong>4.<\/strong> F\u00fcr den Snack zwischendurch holst du dir den &#8222;<a href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">Lagerbier Lolly<\/a>&#8222;, der dich auch nach einem harten Arbeitstag, oder einem harten Wiesentag, wieder auf Touren bringt und dich f\u00fcr den Abend auf die n\u00e4chsten Ma\u00dfe vorbereitet!<\/p>\n\n\n\n<p><strong>5.<\/strong> Nat\u00fcrlich nimmst du am Abend zu deinen Kumpels unseren &#8222;<a href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">Handwerker Sixpack<\/a>&#8220; mit, damit du gleich deinen Bizeps f\u00fcr das Bierkrug-St\u00e4mmen trainieren kannst. Nat\u00fcrlich nebenher das Trinken. Wir wollen ja nicht, dass du unterm Tisch liegst.<\/p>\n\n\n\n<p><strong>6.<\/strong>\u00a0Und wenn wirklich jede Hilfe zu sp\u00e4t ist und du nach deinen Trainingswochen immer noch einen H\u00f6llen-Kater hast, dann solltest du unser &#8222;<a href=\"https:\/\/www.radbag.de\/oktoberfest\" target=\"_blank\" rel=\"noreferrer noopener\">Super Dad Survival Kit<\/a>&#8220; einpacken. Es wird dir dein Leben retten. Glaub mir. Auch wenn du vielleicht noch kein Vater bist, wer wei\u00df, was das Oktoberfest mit sich bringt.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote.jpg\" alt=\"Oktoberfest Spr\u00fcche\" class=\"wp-image-7889\" srcset=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote.jpg 1000w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote-250x250.jpg 250w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote-300x300.jpg 300w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote-720x720.jpg 720w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote-480x480.jpg 480w, https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/Quote-160x160.jpg 160w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Nun denn: viel Durchhalteverm\u00f6gen, wir glauben an dich! \ud83e\udd68\ud83d\udcaa\ud83c\udf7b<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Prost,<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\">\ud83c\udf7b <strong>dein radbag Team<\/strong> \ud83c\udf7b<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Oktoberfest Wie du das Fest der Feste \u00fcberlebst Der leckere Duft von W\u00fcrstchen in der Luft, die St\u00e4nde voller Brezel, der leicht s\u00fc\u00dfe Geschmack von Senf und die Menschenmenge in Dirndl und Lederhosen mit sch\u00f6nen Frisuren und Lebkuchenherzen um den Hals. Und nat\u00fcrlich Bier. Bier ohne Ende. Ja, wir sprechen hier vom ber\u00fchmt, ber\u00fcchtigten Oktoberfest,&hellip;<\/p>\n","protected":false},"author":14,"featured_media":7887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,112],"tags":[254,253],"class_list":["post-7882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anlass","category-geschenkeguide","tag-muenchen","tag-oktoberfest"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oktoberfest - Der Survival-Guide f\u00fcr das Fest<\/title>\n<meta name=\"description\" content=\"Wie du am besten das Oktoberfest \u00fcberleben wirst? Mit unserem genialen Survival Guide nat\u00fcrlich! \u2705 Jetzt lesen &amp; f\u00fcrs Leben lernen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oktoberfest - Der Survival-Guide f\u00fcr das Fest\" \/>\n<meta property=\"og:description\" content=\"Wie du am besten das Oktoberfest \u00fcberleben wirst? Mit unserem genialen Survival Guide nat\u00fcrlich! \u2705 Jetzt lesen &amp; f\u00fcrs Leben lernen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide\" \/>\n<meta property=\"og:site_name\" content=\"Der Blog von radbag\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-31T13:15:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-02T07:26:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Johanna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Johanna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide\",\"url\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide\",\"name\":\"Oktoberfest - Der Survival-Guide f\u00fcr das Fest\",\"isPartOf\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg\",\"datePublished\":\"2017-08-31T13:15:11+00:00\",\"dateModified\":\"2022-09-02T07:26:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d\"},\"description\":\"Wie du am besten das Oktoberfest \u00fcberleben wirst? Mit unserem genialen Survival Guide nat\u00fcrlich! \u2705 Jetzt lesen & f\u00fcrs Leben lernen!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#primaryimage\",\"url\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg\",\"contentUrl\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg\",\"width\":1000,\"height\":648},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.radbag.de\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oktoberfest &#8211; Der Survival-Guide\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radbag.de\/blog\/#website\",\"url\":\"https:\/\/www.radbag.de\/blog\/\",\"name\":\"Der Blog von radbag\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radbag.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d\",\"name\":\"Johanna\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png\",\"contentUrl\":\"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png\",\"caption\":\"Johanna\"},\"description\":\"Johanna k\u00fcmmert sich um alles was mit E-Commerce zu tun hat und verfasst f\u00fcr euch spannende Blogbeitr\u00e4ge die euer Leben leichter machen sollen. Wenn sie euch das Leben gerade nicht leichter macht, ist sie entweder auf der ganzen Welt oder am Tanzen zu finden.\",\"url\":\"https:\/\/www.radbag.de\/blog\/author\/johanna\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oktoberfest - Der Survival-Guide f\u00fcr das Fest","description":"Wie du am besten das Oktoberfest \u00fcberleben wirst? Mit unserem genialen Survival Guide nat\u00fcrlich! \u2705 Jetzt lesen & f\u00fcrs Leben lernen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide","og_locale":"de_DE","og_type":"article","og_title":"Oktoberfest - Der Survival-Guide f\u00fcr das Fest","og_description":"Wie du am besten das Oktoberfest \u00fcberleben wirst? Mit unserem genialen Survival Guide nat\u00fcrlich! \u2705 Jetzt lesen & f\u00fcrs Leben lernen!","og_url":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide","og_site_name":"Der Blog von radbag","article_published_time":"2017-08-31T13:15:11+00:00","article_modified_time":"2022-09-02T07:26:46+00:00","og_image":[{"width":1000,"height":648,"url":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg","type":"image\/jpeg"}],"author":"Johanna","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Johanna","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide","url":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide","name":"Oktoberfest - Der Survival-Guide f\u00fcr das Fest","isPartOf":{"@id":"https:\/\/www.radbag.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#primaryimage"},"image":{"@id":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#primaryimage"},"thumbnailUrl":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg","datePublished":"2017-08-31T13:15:11+00:00","dateModified":"2022-09-02T07:26:46+00:00","author":{"@id":"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d"},"description":"Wie du am besten das Oktoberfest \u00fcberleben wirst? Mit unserem genialen Survival Guide nat\u00fcrlich! \u2705 Jetzt lesen & f\u00fcrs Leben lernen!","breadcrumb":{"@id":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#primaryimage","url":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg","contentUrl":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2017\/08\/header17.jpg","width":1000,"height":648},{"@type":"BreadcrumbList","@id":"https:\/\/www.radbag.de\/blog\/oktoberfest-der-survival-guide#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.radbag.de\/blog"},{"@type":"ListItem","position":2,"name":"Oktoberfest &#8211; Der Survival-Guide"}]},{"@type":"WebSite","@id":"https:\/\/www.radbag.de\/blog\/#website","url":"https:\/\/www.radbag.de\/blog\/","name":"Der Blog von radbag","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radbag.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/1576d22e194f98997a9b2272013bcf2d","name":"Johanna","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.radbag.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png","contentUrl":"https:\/\/www.radbag.de\/blog\/wp-content\/uploads\/2021\/11\/Johanna-Barberi-MH-Direkt-96x96.png","caption":"Johanna"},"description":"Johanna k\u00fcmmert sich um alles was mit E-Commerce zu tun hat und verfasst f\u00fcr euch spannende Blogbeitr\u00e4ge die euer Leben leichter machen sollen. Wenn sie euch das Leben gerade nicht leichter macht, ist sie entweder auf der ganzen Welt oder am Tanzen zu finden.","url":"https:\/\/www.radbag.de\/blog\/author\/johanna"}]}},"_links":{"self":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts\/7882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/comments?post=7882"}],"version-history":[{"count":12,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts\/7882\/revisions"}],"predecessor-version":[{"id":19788,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/posts\/7882\/revisions\/19788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/media\/7887"}],"wp:attachment":[{"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/media?parent=7882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/categories?post=7882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radbag.de\/blog\/wp-json\/wp\/v2\/tags?post=7882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}